{"id":5004,"date":"2021-06-16T11:23:50","date_gmt":"2021-06-16T09:23:50","guid":{"rendered":"https:\/\/xelaprop.com\/politica-de-privacidad\/"},"modified":"2023-04-18T10:56:21","modified_gmt":"2023-04-18T08:56:21","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/xelaprop.com\/en\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"quien-es-el-responsable-del-tratamiento-de-datos-personales\">\u00bfQui\u00e9n es el Responsable del Tratamiento de datos personales?<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Empresa titular de la p\u00e1gina web:\u00a0 2009GRUPALEX S.L. (En adelante Xela Properties)<\/li>\n\n\n\n<li>NIF: B-65046674<\/li>\n\n\n\n<li>Direcci\u00f3n: Calle Llacuna 22, 4\u00ba 8\u00aa \u2013 08005 BARCELONA<\/li>\n\n\n\n<li>Correo electr\u00f3nico: <a href=\"mailto:%20info@xelaprop.com\">&nbsp;info@xelaprop.com<\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"como-hemos-obtenido-sus-datos\">\u00bfC\u00f3mo hemos obtenido sus datos?<\/h3>\n\n\n\n<p><strong>Nos los ha facilitado usted:<\/strong> &nbsp;bien sea on-line u off-line, al solicitar nuestros servicios como agentes inmobiliarios para poder mantener la relaci\u00f3n jur\u00eddico-comercial con usted o enviarle informaci\u00f3n acerca de nuestros servicios y promociones. &nbsp;<\/p>\n\n\n\n<p>Cuando nos facilite datos personales, garantiza que est\u00e1 habilitado para facilitar esta informaci\u00f3n y que la misma es cierta, veraz, exacta y actualizada, que no es confidencial, que no viola ninguna restricci\u00f3n contractual o derechos de terceros y se compromete a no suplantar a otros usuarios.<\/p>\n\n\n\n<p>Formularios web en los que recopilamos datos personales:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Formulario de contacto: nombre, apellidos, email, tel\u00e9fono.<\/li>\n\n\n\n<li>Formulario para petici\u00f3n de valoraci\u00f3n de inmueble: nombre, apellidos, email, tel\u00e9fono, breve descripci\u00f3n del inmueble.<\/li>\n\n\n\n<li>Formulario para solicitar informaci\u00f3n sobre un inmueble: nombre, email, tel\u00e9fono.<\/li>\n<\/ol>\n\n\n\n<p><strong>Los hemos obtenido de forma autom\u00e1tica: <\/strong>&nbsp;si los datos nos los ha aportado a trav\u00e9s de este sitio web o cualquiera de sus subdominios y\/0, microsites, recopilamos informaci\u00f3n, por ejemplo, cuando accede a la p\u00e1gina, cuando rellena cualquier formulario con datos personales, cuando carga informaci\u00f3n o contenidos (por ejemplo, en nuestro blog), o cuando se comunica con nosotros directamente por correo electr\u00f3nico.<\/p>\n\n\n\n<p>Cuando visita nuestra web se env\u00edan datos desde su navegador a nuestro servidor, para optimizar nuestros servicios y mejorar su experiencia como usuario, por ejemplo, cuando accede a la p\u00e1gina o cuando inicia sesi\u00f3n a trav\u00e9s de servicios de terceros como redes sociales.&nbsp; Esos datos pueden ser recogidos y almacenados autom\u00e1ticamente por nosotros o por terceros en nuestro nombre. Estos datos pueden incluir:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la direcci\u00f3n IP del usuario<\/li>\n\n\n\n<li>la fecha y la hora de la visita<\/li>\n\n\n\n<li>la URL del sitio del que proviene el usuario<\/li>\n\n\n\n<li>las p\u00e1ginas visitadas en nuestro sitio web<\/li>\n\n\n\n<li>informaci\u00f3n sobre el navegador utilizado (tipo y versi\u00f3n del navegador, sistema operativo, etc.).<\/li>\n<\/ul>\n\n\n\n<p>Podemos tratar y registrar dichos usos, sesiones e informaci\u00f3n relacionada, ya sea en forma independiente o con la ayuda de servicios de terceros, incluso mediante el uso de cookies.<\/p>\n\n\n\n<p>En el caso de que nuestro sitio web disponga de conectores a redes sociales, cuando elige interactuar con nosotros a trav\u00e9s de una red social, nosotros no podemos responsabilizarnos de la configuraci\u00f3n de privacidad elegida por el usuario, pudiendo la red social informar sobre su direcci\u00f3n IP o qu\u00e9 p\u00e1gina est\u00e1 visitando en nuestro sitio web y puede establecer una cookie para permitirles funcionar correctamente. Su nombre figurar\u00e1 en los likes que otorgue o en los comentarios que realizas en nuestra p\u00e1gina en una red social. Si no quiere que figuren datos personales suyos asociados a esos likes o comentarios configure su privacidad para evitarlo, seudonimizando sus datos por ejemplo poni\u00e9ndote un nickname o alias que no revele su nombre y apellidos.<\/p>\n\n\n\n<p>Si inicia la sesi\u00f3n en una de estas redes sociales durante su visita de nuestro sitio web, la red social podr\u00e1 a\u00f1adir esa informaci\u00f3n a su perfil y esa informaci\u00f3n ser\u00e1 transferida a la red social. Si no quiere que se realice esa trasferencia de datos, salga de su sesi\u00f3n en la red social antes de entrar en nuestros sitios web o aplicaciones m\u00f3viles, ya que no est\u00e1 en nuestra mano influir en esta recogida y trasferencia de datos a trav\u00e9s de los conectores sociales.<\/p>\n\n\n\n<p>Si como usuario, a trav\u00e9s de nuestra p\u00e1gina oficial en una red social, decide publicar y\/o compartir textos, fotos, v\u00eddeos y otro tipo de informaci\u00f3n y\/o contenidos ser\u00e1s el \u00fanico responsable de que dichos contenidos cumplan la normativa legal correspondiente.<\/p>\n\n\n\n<p>En todo caso, podremos eliminar tanto de esta p\u00e1gina web como de nuestras p\u00e1ginas en redes sociales, cualquier contenido publicado cuando detectemos que has vulnerado la legislaci\u00f3n vigente, y los t\u00e9rminos indicados en esta pol\u00edtica de privacidad y en las condiciones generales recogidas en nuestro Aviso Legal.<\/p>\n\n\n\n<p>Las Redes Sociales no est\u00e1n alojadas directamente en nuestros servicios. Sus interacciones con ellas se rigen por sus pol\u00edticas y no por las nuestras. Lea las pol\u00edticas de privacidad de esas redes sociales para tener informaci\u00f3n detallada sobre la recogida y transferencia de datos personales, sus derechos y sobre la configuraci\u00f3n de su privacidad.&nbsp;<\/p>\n\n\n\n<p>Para comprobar que los formularios de este web se utilizan por personas, y no por medios automatizados, usamos la tecnolog\u00eda \u201cInvisible reCAPTCHA\u201d de Google. Al utilizarla, se recogen y env\u00edan en Google, por su an\u00e1lisis, informaciones relativas al hardware y software del dispositivo usado por el usuario, de acuerdo con la <a href=\"https:\/\/policies.google.com\/privacy?hl=es\" target=\"_blank\" rel=\"noopener\">pol\u00edtica de privacidad (de Google)<\/a> y los <a href=\"https:\/\/policies.google.com\/terms?hl=es\" target=\"_blank\" rel=\"noopener\">T\u00e9rminos de uso (de Google).<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"que-edad-he-de-tener-para-hacer-uso-de-esta-pagina-web\">\u00bfQu\u00e9 edad he de tener para hacer uso de esta p\u00e1gina web?<\/h3>\n\n\n\n<p>Quien facilita los datos a trav\u00e9s de los formularios de esta web y acepta su tratamiento declara ser mayor de edad. Si en alg\u00fan momento, detectamos que un menor ha proporcionado datos de car\u00e1cter personal, procederemos a la cancelaci\u00f3n de los mismos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"que-debe-saber-antes-de-compartir-datos-de-terceros\">\u00bfQu\u00e9 debe saber antes de compartir datos de terceros?<\/h3>\n\n\n\n<p>Con respecto a los datos de otras personas, debe respetar su privacidad prestando especial cuidado a la hora de publicar sus datos de car\u00e1cter personal. Le recordamos que, como usuario, s\u00f3lo facilite y consienta el tratamiento de sus datos personales, pero no de terceros, si nos facilita datos de terceros est\u00e1 haciendo una cesi\u00f3n de datos de car\u00e1cter personal, siendo su responsabilidad contar con el consentimiento previo y expreso de esos terceros para utilizarlos y facilit\u00e1rnoslos, usted se hace responsable de informarles de la inclusi\u00f3n de sus datos en nuestros tratamientos.<br><\/p>\n\n\n\n<p>La publicaci\u00f3n de datos de terceros sin su consentimiento puede infringir, adem\u00e1s de la normativa sobre protecci\u00f3n de datos, el derecho al honor, a la intimidad o a la propia imagen, derechos cuya protecci\u00f3n se rige por lo dispuesto en la Ley Org\u00e1nica 1\/1982, de 5 de mayo, de protecci\u00f3n civil del derecho al honor, a la intimidad personal y familiar y a la propia imagen.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"que-fines-les-damos-a-los-datos-personales-que-recopilamos\">\u00bfQu\u00e9 fines les damos a los datos personales que recopilamos?<\/h3>\n\n\n\n<p>Los datos los podemos tratar para distintas finalidades, por ejemplo:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Para el proceso de compra-venta y alquiler de los inmuebles que tenemos en cartera.<\/li>\n\n\n\n<li>Para responder a su consulta para poder aclararle las dudas y cuestiones que nos haya expuesto.&nbsp;<\/li>\n\n\n\n<li>Para contactar con usted por los medios que no haya indicado, e-mail, tel\u00e9fono, etc.<\/li>\n\n\n\n<li>En relaci\u00f3n a las informaciones recopiladas autom\u00e1ticamente por la p\u00e1gina web, en base a su navegaci\u00f3n como usuario, creamos informaciones an\u00f3nimas y agregadas sobre su comportamiento, efectos de segmentaci\u00f3n y desarrollo de perfiles an\u00f3nimos.<\/li>\n<\/ol>\n\n\n\n<p>Esta interacci\u00f3n nos ayuda a: mejorar el rendimiento de la p\u00e1gina web, promover una experiencia m\u00e1s personalizada, medir y monitorizar la eficiencia de la p\u00e1gina web, gestionar la p\u00e1gina web, de modo que se garantice que la misma se vuelve cada vez m\u00e1s segura y transparente.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Realizar encuestas de opini\u00f3n y\/o satisfacci\u00f3n y remitirte, mediante comunicaciones electr\u00f3nicas, informaci\u00f3n sobre nuestras actividades, productos y\/o servicios (incluidas comunicaciones publicitarias y\/o comerciales a los efectos del art. 21 LSSICE 34\/2002). Si ya tenemos una relaci\u00f3n contractual previa, dichas comunicaciones las remitiremos sobre la base de nuestro inter\u00e9s leg\u00edtimo (Art. 6 ap. 1 letra f RGPD). En el caso de no tener una relaci\u00f3n contractual previa, solo le mandaremos ese tipo de comunicaciones, si nos lo autoriza marcando la opci\u00f3n (opt-in) que expresamente se incluye al efecto en los formularios correspondientes (Art. 6 ap. 1 letra a RGPD). Las comunicaciones electr\u00f3nicas que le enviemos incluir\u00e1n, en la propia comunicaci\u00f3n, la opci\u00f3n de dejar de recibirlas.<\/li>\n\n\n\n<li>Podremos hacer fotograf\u00edas y\/o videos en las actividades, o eventos que organicemos y\/o promocionemos, para informar sobre ellos, documentarlos, y formar parte de la memoria fotogr\u00e1fica\/videogr\u00e1fica de la empresa.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"durante-cuanto-tiempo-conservaremos-sus-datos-personales\">\u00bfDurante cu\u00e1nto tiempo conservaremos sus datos personales?<\/h3>\n\n\n\n<p>Sus datos personales los conservaremos mientras no nos solicite su supresi\u00f3n. Incluso solicitada la misma, podremos mantenerlos durante el tiempo necesario y limitando su tratamiento (bloque\u00e1ndolos), \u00fanicamente para cumplir con las obligaciones legales\/contractuales a que estemos sometidos y\/o durante los plazos legales previstos para la prescripci\u00f3n de cualesquiera responsabilidades por nuestra parte y\/o el ejercicio o la defensa de reclamaciones derivadas de la relaci\u00f3n mantenida.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"que-causas-de-legitimacion-utilizamos-para-tratar-sus-datos\">\u00bfQu\u00e9 causas de legitimaci\u00f3n utilizamos para tratar sus datos?<\/h3>\n\n\n\n<p>Las causas de legitimaci\u00f3n son las que nos permiten y habilitan a poder tratar sus datos personales de forma legal. Hay diferentes causas de legitimaci\u00f3n o bases jur\u00eddicas que nos permiten tratar sus datos de forma l\u00edcita y legal:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Puede serlo la relaci\u00f3n jur\u00eddico-comercial existente entre las partes, en el caso de que sea un cliente o potencial cliente.<\/li>\n\n\n\n<li>Puede serlo tambi\u00e9n, su consentimiento si nos ha realizado una solicitud a trav\u00e9s de nuestra p\u00e1gina web. Dicho consentimiento nos lo otorga de forma inequ\u00edvoca al facilitarnos sus datos on-line u off-line, consider\u00e1ndose dicha aportaci\u00f3n un acto afirmativo claro que manifiesta dicho consentimiento. La aportaci\u00f3n de los datos solicitados es obligatoria por ser imprescindibles para atender su petici\u00f3n; si no los facilita, no podremos llevarla a cabo. Podr\u00e1 retirar ese consentimiento en cualquier momento remiti\u00e9ndonos un e-mail en tal sentido a <a href=\"mailto:info@xelaprop.com\">info@xelaprop.com<\/a> dicha retirada supone que no podremos prestarle los servicios solicitados o atender a sus consultas o peticiones.<\/li>\n\n\n\n<li>Seg\u00fan establece el Considerando 47 del RGPD (Reglamento Europeo General de Protecci\u00f3n de Datos Personales 2016\/ 679 de 27-4-2016), tambi\u00e9n constituye una base jur\u00eddica para tratar sus datos nuestro inter\u00e9s leg\u00edtimo para:<\/li>\n<\/ol>\n\n\n\n<p>Informarle de nuestras actividades, productos y\/o servicios (incluso mediante comunicaciones electr\u00f3nicas) o de aquellas entidades terceras con las que hayamos suscrito acuerdo de colaboraci\u00f3n. Si ya tenemos una relaci\u00f3n contractual previa, dichas comunicaciones las remitiremos sobre la base de nuestro inter\u00e9s leg\u00edtimo. En el caso contrario, solo le mandaremos ese tipo de comunicaciones, si nos da su consentimiento marcando la opci\u00f3n que expresamente se incluye al efecto en los formularios correspondientes. En todo caso, las comunicaciones electr\u00f3nicas que te enviemos incluir\u00e1n, en la propia comunicaci\u00f3n, la opci\u00f3n de dejar de recibirlas en lo sucesivo.<\/p>\n\n\n\n<p>En todo caso, el tratamiento indicado de sus datos consideramos que es proporcionado y supone un impacto m\u00ednimo en su privacidad, pero siempre prevalecer\u00e1n, sobre nuestro inter\u00e9s leg\u00edtimos, sus intereses, derechos o libertades, por lo que, si no desea que tratemos sus datos para estas finalidades rem\u00edtanos por favor un e-mail en tal sentido a <a href=\"mailto:info@xelaprop.com\">info@xelaprop.com<\/a> y as\u00ed lo haremos, pudiendo mantenerlos bloqueados para la formulaci\u00f3n, ejercicio o defensa de reclamaciones. La retirada de su consentimiento para tratar sus datos para esas finalidades no condiciona el tratamiento de sus datos para el resto de finalidades descritas en la pol\u00edtica de privacidad.<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-quien-podremos-comunicar-los-datos-personales-que-nos-facilite\">\u00bfA qui\u00e9n podremos comunicar los datos personales que nos facilite?<\/h3>\n\n\n\n<p>Sus datos personales no se transferir\u00e1n a terceros, excepto que:<\/p>\n\n\n\n<p>Tengamos su autorizaci\u00f3n expresa.<\/p>\n\n\n\n<p>Los terceros sean proveedores que nos suministren productos y servicios (encargados de tratamiento) y la comunicaci\u00f3n sea un requisito para cumplir con nuestras obligaciones derivadas de un contrato o pre-contrato con usted.<\/p>\n\n\n\n<p>Una Ley o norma con rango de Ley nos exija la comunicaci\u00f3n de datos a entidades organismos (AEAT, etc.)<\/p>\n\n\n\n<p>La comunicaci\u00f3n fuese estrictamente necesario para asegurar el cumplimiento de nuestros t\u00e9rminos de uso, derechos o titularidad.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"como-utilizamos-las-redes-sociales-corporativas\"><strong>\u00bfC\u00f3mo utilizamos las Redes Sociales corporativas?<\/strong><\/h3>\n\n\n\n<p>El objeto de las herramientas como Facebook, Twitter, LinkedIn, Instagram, etc. u otras redes sociales es dar visibilidad y difusi\u00f3n a las actividades que desarrollamos. Estas herramientas almacenan datos personales en los servidores de los servicios respectivos y se rigen por su propia pol\u00edtica de privacidad. Le recomendamos que lea y revise las condiciones de uso y pol\u00edtica de privacidad de la red social en el momento de registrarse, teniendo en cuenta las diferentes posibilidades de configuraci\u00f3n en relaci\u00f3n al grado de privacidad del perfil de usuario en la red social.<br>Nos reservamos el derecho de eliminar de nuestras redes sociales cualquier informaci\u00f3n publicada por terceros que vulnere la legalidad, incite a hacerlo o contenga mensajes que atenten contra la dignidad de personas o instituciones. Como tambi\u00e9n el derecho a bloquear o denunciar el perfil autor de estos mensajes.<br><\/p>\n\n\n\n<p><strong>Redes Sociales en las que est\u00e1 presente Xela Properties:<\/strong><\/p>\n\n\n\n<p>Instagram: <a href=\"https:\/\/www.instagram.com\/xelaproperties\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com\/xelaproperties\/<\/a><br>Facebook: <a href=\"https:\/\/www.facebook.com\/pg\/Xelaprop\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/pg\/Xelaprop\/<\/a><br>Linkedin: <a href=\"https:\/\/www.linkedin.com\/company\/xela-properties-real-estate\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/company\/xela-properties-real-estate\/<\/a><\/p>\n\n\n\n<p><strong>\u00bfRealizamos transferencias internacionales de sus datos personales?<\/strong><\/p>\n\n\n\n<p>Una&nbsp;transferencia internacional de datos&nbsp;se produce cuando los&nbsp;datos&nbsp;personales que son tratados por un responsable o un encargado del tratamiento en el Espacio Econ\u00f3mico Europeo (pa\u00edses de la Uni\u00f3n Europea, Islandia, Liechtenstein y Noruega) son enviados a un tercer pa\u00eds u organizaci\u00f3n&nbsp;internacional, fuera de dicho&nbsp;territorio.<\/p>\n\n\n\n<p>Nuestros proveedores que puedan tener acceso a datos personales, con la finalidad de&nbsp; prestarnos servicios auxiliares a nuestra actividad&nbsp; (alojamiento, housing, software as a service, copias de seguridad en remoto, servicios de soporte o mantenimiento inform\u00e1tico, gestores de correo electr\u00f3nico, env\u00edo de e-mails y e-mail marketing, transferencia de archivos etc \u2026), tienen sus centros de procesamiento de datos dentro del Espacio, Econ\u00f3mico Europeo o en pa\u00edses con un mismo nivel de adecuaci\u00f3n seg\u00fan establece la Comisi\u00f3n Europea y el Comit\u00e9 Europeo de Protecci\u00f3n de Datos.&nbsp;<\/p>\n\n\n\n<p>Nuestros encargados de tratamiento con servicios en la nube:<br>Como encargados de tratamiento, tenemos contratados a los siguientes proveedores de servicios:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Google Ireland Limited, con domicilio en Google Building Gordon House, Barrow St, Dublin 4, Irlanda, presta servicios de anal\u00edtica web y servicios globales de internet, e-mail, almacenamiento en la nube, publicidad. Puede consultar la pol\u00edtica de privacidad y dem\u00e1s aspectos legales de la compa\u00f1\u00eda en el siguiente enlace: <a href=\"https:\/\/www.blog.google\/around-the-globe\/google-europe\/some-changes-our-service-model-europe\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.blog.google\/around-the-globe\/google-europe\/some-changes-our-service-model-europe\/<\/a>&nbsp; y&nbsp; <a href=\"https:\/\/policies.google.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/<\/a>&nbsp;<\/li>\n\n\n\n<li>Facebook Ireland Ltd., con domicilio en 4 Grand Canal Square, Grand Canal Harbour, Dubl\u00edn 2, Irlanda, presta servicios de interacci\u00f3n mediante redes sociales, anal\u00edtica social, publicidad. Puede consultar la pol\u00edtica de privacidad y dem\u00e1s aspectos legales de la compa\u00f1\u00eda en el siguiente enlace <a href=\"https:\/\/www.facebook.com\/full_data_use_policy%20\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/full_data_use_policy<\/a> y <a href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\" rel=\"noopener\">https:\/\/help.instagram.com\/519522125107875<\/a><\/li>\n\n\n\n<li>Instagram producto proporcionado por Facebook Ireland Ltd. presta servicios de interacci\u00f3n mediante redes sociales, anal\u00edtica social, publicidad. Puede consultar la pol\u00edtica de privacidad y dem\u00e1s aspectos legales de la compa\u00f1\u00eda en el siguiente enlace <a href=\"https:\/\/es-la.facebook.com\/help\/instagram\/478745558852511\" target=\"_blank\" rel=\"noopener\">https:\/\/es-la.facebook.com\/help\/instagram\/478745558852511<\/a><\/li>\n\n\n\n<li>LinkedIn Ireland Unlimited Company, con domicilio en Wilton Plaza, Wilton Place, Dubl\u00edn 2, Irlanda, presta servicios de interacci\u00f3n mediante redes sociales, anal\u00edtica social, publicidad, etc. Puede consultar la pol\u00edtica de privacidad y dem\u00e1s aspectos legales de la compa\u00f1\u00eda en el siguiente enlace <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a><\/li>\n\n\n\n<li>Whatsapp&nbsp; producto proporcionado por WhatsApp Inc. propiedad de Facebook Ireland Ltd., presta servicios de mensajer\u00eda instant\u00e1nea. Puede consultar la pol\u00edtica de privacidad y dem\u00e1s aspectos legales de la compa\u00f1\u00eda en el siguiente enlace: <a href=\"https:\/\/www.whatsapp.com\/legal\/business-policy\/?lang=es\" target=\"_blank\" rel=\"noopener\">https:\/\/www.whatsapp.com\/legal\/business-policy\/?lang=es<\/a> y <a href=\"https:\/\/www.whatsapp.com\/legal\/privacy-policy-eea\" target=\"_blank\" rel=\"noopener\">https:\/\/www.whatsapp.com\/legal\/privacy-policy-eea<\/a><\/li>\n\n\n\n<li>France Dropbox: Ps. la Castellana, n\u00ba 259 28046, Madrid, Espa\u00f1a, presta servicios de almacenamiento en la nube. Puede consultar la pol\u00edtica de privacidad y dem\u00e1s aspectos legales de la compa\u00f1\u00eda en el siguiente enlace: <a href=\"https:\/\/www.dropbox.com\/privacy?trigger=business_landing-t61fl_footer\" target=\"_blank\" rel=\"noopener\">https:\/\/www.dropbox.com\/privacy?trigger=business_landing-t61fl_footer<\/a><\/li>\n\n\n\n<li>Web alojada en OVH Hosting. OVH HISPANO SL es una filial de la sociedad OVH GROUPE SAS, inscrita en el RCS de Lille con el n\u00famero 537 407 926 sita en 2, rue Kellermann, 59100 Roubaix. &nbsp;El Centro de Procesamiento de Datos y los servidores est\u00e1n alojados en Francia. M\u00e1s informaci\u00f3n en: <a href=\"https:\/\/www.ovh.es\/proteccion-datos-personales\/faq.xml\" target=\"_blank\" rel=\"noopener\">https:\/\/www.ovh.es\/proteccion-datos-personales\/faq.xml<\/a><\/li>\n<\/ol>\n\n\n\n<p><strong>\u00bfQu\u00e9 Derechos puede ejercitar?<\/strong><br>Son los conocidos como Derechos ARCO-POL, puede ejercitarlos enviando un e-mail a: <a href=\"mailto:%20info@xelaprop.com\">&nbsp;info@xelaprop.com<\/a> Puede, cuando procedan, ejercitar sus derechos de acceso, rectificaci\u00f3n, supresi\u00f3n, de limitaci\u00f3n y oposici\u00f3n a su tratamiento, as\u00ed como a no ser objeto de decisiones basadas \u00fanicamente en el tratamiento automatizado de sus datos, en la direcci\u00f3n de correo postal o electr\u00f3nico indicadas al principio de esta pol\u00edtica de privacidad; en ambos casos mediante solicitud escrita y firmada adjuntando copia del DNI o pasaporte u otro documento v\u00e1lido que le identifique. En caso de modificaci\u00f3n de sus datos deber\u00e1 notificarlo en la misma direcci\u00f3n, declinando esta empresa toda responsabilidad en caso de no hacerlo<br><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Derecho de acceso:<\/strong> Puede preguntarnos qu\u00e9 datos personales estamos tratando incluso solicitarnos una copia de estos.<\/li>\n\n\n\n<li><strong>Derecho de rectificaci\u00f3n<\/strong>: Puede solicitarnos la rectificaci\u00f3n de los datos personales inexactos o que completemos los que sean incompletos, inclusive mediante una declaraci\u00f3n adicional.<\/li>\n\n\n\n<li><strong>Derecho de supresi\u00f3n (derecho al olvido):<\/strong> Puede solicitarnos la supresi\u00f3n de sus datos personales cuando: no sean necesarios para los fines para los que fueron recogidos, retire su consentimiento, haya habido un tratamiento il\u00edcito de los mismos o por cumplimiento de una obligaci\u00f3n legal.<\/li>\n\n\n\n<li><strong>Derecho a la limitaci\u00f3n del tratamiento:<\/strong> Puede solicitarnos la limitaci\u00f3n del tratamiento de sus datos, en cuyo caso \u00fanicamente los conservaremos para el ejercicio o la defensa de reclamaciones.<\/li>\n\n\n\n<li><strong>Derecho de oposici\u00f3n:<\/strong> Puede oponerse al tratamiento que se haga de sus datos si dicho tratamiento se base en el inter\u00e9s leg\u00edtimo del responsable del fichero o es para fines publicitarios.<br><br>Una vez recibida cualquiera de las anteriores solicitudes le responderemos en los plazos legalmente establecidos. Puede reclamar ante la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos. Si desea m\u00e1s informaci\u00f3n acerca de los derechos que puede ejercitar y para la solicitud de modelos de formularios de ejercicio de derechos puede visitar la p\u00e1gina web de la Agencia espa\u00f1ola de Protecci\u00f3n de Datos, <a href=\"http:\/\/www.aepd.es\" target=\"_blank\" rel=\"noopener\">www.aepd.es<\/a>&nbsp;&nbsp;<br><\/li>\n<\/ul>\n\n\n\n<p><strong>\u00bfQu\u00e9 categor\u00edas de datos tratamos?<\/strong><br>El RGPD establece dos categor\u00edas de datos personales, los conocidos como datos identificativos y los conocidos como categor\u00edas especiales: origen \u00e9tnico o racial, opiniones pol\u00edticas, convicciones religiosas o filos\u00f3ficas, afiliaci\u00f3n sindical, datos gen\u00e9ticos o de salud, datos biom\u00e9tricos, datos relativos a la vida u orientaciones sexuales.<\/p>\n\n\n\n<p>Las categor\u00edas de datos que tratamos son datos de identificativos, no tratamos datos considerados como categor\u00edas especiales de datos (gen\u00e9ticos, biom\u00e9tricos, etc.). Los datos bancarios para las compras a trav\u00e9s de nuestro e-commerce son tratados a trav\u00e9s de una pasarela de pagos segura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n es el Responsable del Tratamiento de datos personales? \u00bfC\u00f3mo hemos obtenido sus datos? Nos los ha facilitado usted: &nbsp;bien sea on-line u off-line, al solicitar nuestros servicios como agentes &#8230; <a title=\"Pol\u00edtica de privacidad\" class=\"read-more\" href=\"https:\/\/xelaprop.com\/en\/politica-de-privacidad\/\" aria-label=\"Read more about Pol\u00edtica de privacidad\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":4707,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"wpupg_custom_link":[],"wpupg_custom_link_behaviour":[],"wpupg_custom_link_nofollow":[],"wpupg_custom_image":[],"wpupg_custom_image_id":[],"_joinchat":[],"footnotes":""},"class_list":{"0":"post-5004","1":"page","2":"type-page","3":"status-publish","4":"has-post-thumbnail","6":"infinite-scroll-item","7":"no-featured-image-padding"},"acf":[],"_links":{"self":[{"href":"https:\/\/xelaprop.com\/en\/wp-json\/wp\/v2\/pages\/5004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xelaprop.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xelaprop.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xelaprop.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/xelaprop.com\/en\/wp-json\/wp\/v2\/comments?post=5004"}],"version-history":[{"count":1,"href":"https:\/\/xelaprop.com\/en\/wp-json\/wp\/v2\/pages\/5004\/revisions"}],"predecessor-version":[{"id":10226,"href":"https:\/\/xelaprop.com\/en\/wp-json\/wp\/v2\/pages\/5004\/revisions\/10226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xelaprop.com\/en\/wp-json\/wp\/v2\/media\/4707"}],"wp:attachment":[{"href":"https:\/\/xelaprop.com\/en\/wp-json\/wp\/v2\/media?parent=5004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}